{"id":3825,"date":"2024-10-17T04:09:42","date_gmt":"2024-10-17T04:09:42","guid":{"rendered":"https:\/\/kerjasama.usk.ac.id\/?p=3825"},"modified":"2024-10-22T04:16:35","modified_gmt":"2024-10-22T04:16:35","slug":"usk-dan-zurich-syariah-kolaborasi-perkuat-transformasi-digital","status":"publish","type":"post","link":"https:\/\/kerjasama.usk.ac.id\/index.php\/2024\/10\/17\/usk-dan-zurich-syariah-kolaborasi-perkuat-transformasi-digital\/","title":{"rendered":"USK dan Zurich Syariah Kolaborasi Perkuat Transformasi Digital"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"3825\" class=\"elementor elementor-3825\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-012c138 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"012c138\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\" data-e-bg-lazyload=\".elementor-background-overlay\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c816145\" data-id=\"c816145\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-53556b3 elementor-widget elementor-widget-heading\" data-id=\"53556b3\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t<style>\/*! elementor - v3.16.0 - 09-10-2023 *\/\n.elementor-heading-title{padding:0;margin:0;line-height:1}.elementor-widget-heading .elementor-heading-title[class*=elementor-size-]>a{color:inherit;font-size:inherit;line-height:inherit}.elementor-widget-heading .elementor-heading-title.elementor-size-small{font-size:15px}.elementor-widget-heading .elementor-heading-title.elementor-size-medium{font-size:19px}.elementor-widget-heading .elementor-heading-title.elementor-size-large{font-size:29px}.elementor-widget-heading .elementor-heading-title.elementor-size-xl{font-size:39px}.elementor-widget-heading .elementor-heading-title.elementor-size-xxl{font-size:59px}<\/style><h2 class=\"elementor-heading-title elementor-size-default\">USK dan Zurich Syariah Kolaborasi Perkuat Transformasi Digital<\/h2>\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-2d33246 e-flex e-con-boxed e-con e-parent\" data-id=\"2d33246\" data-element_type=\"container\" data-settings=\"{&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\" data-core-v316-plus=\"true\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6279740 elementor-widget elementor-widget-image\" data-id=\"6279740\" data-element_type=\"widget\" data-widget_type=\"image.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t<style>\/*! elementor - v3.16.0 - 09-10-2023 *\/\n.elementor-widget-image{text-align:center}.elementor-widget-image a{display:inline-block}.elementor-widget-image a img[src$=\".svg\"]{width:48px}.elementor-widget-image img{vertical-align:middle;display:inline-block}<\/style>\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1000\" height=\"665\" src=\"https:\/\/mlzwni2sjjcd.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/kerjasama.usk.ac.id\/wp-content\/uploads\/2024\/10\/IMG_0320.jpg\" class=\"attachment-full size-full wp-image-3827\" alt=\"\" srcset=\"https:\/\/mlzwni2sjjcd.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/kerjasama.usk.ac.id\/wp-content\/uploads\/2024\/10\/IMG_0320.jpg 1000w, https:\/\/mlzwni2sjjcd.i.optimole.com\/w:300\/h:200\/q:mauto\/f:best\/https:\/\/kerjasama.usk.ac.id\/wp-content\/uploads\/2024\/10\/IMG_0320.jpg 300w, https:\/\/mlzwni2sjjcd.i.optimole.com\/w:768\/h:511\/q:mauto\/f:best\/https:\/\/kerjasama.usk.ac.id\/wp-content\/uploads\/2024\/10\/IMG_0320.jpg 768w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-element elementor-element-1432ceb elementor-widget elementor-widget-text-editor\" data-id=\"1432ceb\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t<style>\/*! elementor - v3.16.0 - 09-10-2023 *\/\n.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#69727d;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#69727d;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}<\/style>\t\t\t\t<p>Universitas Syiah Kuala dan Zurich Syariah siap berkolaborasi untuk memperkuat transformasi digital khususnya di bidang asuransi syariah. Komitmen ini ditandai dengan penandatanganan MoU oleh Rektor USK Prof. Dr. Ir. Marwan dengan Direktur Zurich Syariah Auralusia Rimadiana di Aula Fakultas Keperawatan USK. (Banda Aceh, 16 Oktober 2024).<\/p><p>Business Head Partnership Zurich Syariah Satria Nugraha mengatakan, kesepakatan antara USK dengan Zurich Syariah ini bertujuan untuk mendekatkan dunia industri dan akademisi. Khususnya dalam bidang digitalisasi yang sedang perusahaannya lakukan.<\/p><p>Selain dengan USK, kesepakatan yang sama telah Zurich Syariah jalin dengan berbagai perguruan tinggi lainnya. Semua ini adalah bentuk komitmen Zurich Syariah untuk menghadirkan ekosistem digitalisasi yang lebih baik di Indonesia.<\/p><p>\u00a0\u201cKe depannya kita bisa berdiskusi lebih jauh, potensi kerja sama apa saja yang bisa kita lakukan untuk bisa meningkatkan output atau lulusan dari kampus itu sendiri,\u201d ucapnya.<\/p><p>Rektor mengatakan, USK menyambut baik kerja sama ini sebab transformasi digital adalah sebuah keniscayaan yang harus kita hadapi sekarang. Transformasi digital telah menjangkau semua bidang, baik kesehatan, pendidikan, keuangan termasuk dunia asuransi.<\/p><p>\u201cTranformasi digital tidak hanya mempengaruhi cara perusahaan beroperasi, tetapi juga bagaimana masyarakat memahami dan mengakses produk asuransi,\u201d ucap Rektor.<\/p>\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6a42371 e-flex e-con-boxed e-con e-parent\" data-id=\"6a42371\" data-element_type=\"container\" data-settings=\"{&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\" data-core-v316-plus=\"true\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c889abc elementor-widget elementor-widget-image\" data-id=\"c889abc\" data-element_type=\"widget\" data-widget_type=\"image.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1000\" height=\"665\" src=\"https:\/\/mlzwni2sjjcd.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/kerjasama.usk.ac.id\/wp-content\/uploads\/2024\/10\/IMG_0610.jpg\" class=\"attachment-full size-full wp-image-3829\" alt=\"\" srcset=\"https:\/\/mlzwni2sjjcd.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/kerjasama.usk.ac.id\/wp-content\/uploads\/2024\/10\/IMG_0610.jpg 1000w, https:\/\/mlzwni2sjjcd.i.optimole.com\/w:300\/h:200\/q:mauto\/f:best\/https:\/\/kerjasama.usk.ac.id\/wp-content\/uploads\/2024\/10\/IMG_0610.jpg 300w, https:\/\/mlzwni2sjjcd.i.optimole.com\/w:768\/h:511\/q:mauto\/f:best\/https:\/\/kerjasama.usk.ac.id\/wp-content\/uploads\/2024\/10\/IMG_0610.jpg 768w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-element elementor-element-b7cdec2 elementor-widget elementor-widget-text-editor\" data-id=\"b7cdec2\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t\t\t<p>Karena itulah, Rektor berharap kerja sama ini bisa memberi manfaat yang luas bagi Zurich Syariah maupun USK, termasuk pula \u00a0dalam upaya membangun literasi terkait dunia asuransi di kalangan sivitas akademika USK.\u00a0 Apalagi saat ini Aceh telah diberlakukan Syariat Islam, sehingga perlu adanya penyesuaian dalam mengimplementasikan program asuransi.<\/p><p>\u201cKerja sama ini sangat sejalan dengan semangat USK. Pengembangan literasi digital maupun transformasi keuangan digital, semua itu telah lama menjadi perhatian USK. Terima kasih Zurich Syariah atas terjalinnya kolaborasi ini,\u201d ucap Rektor.<\/p><p>Selain itu, Rektor mengatakan USK sangat terbuka dengan peluang-peluang kerja sama lainnya. Misalnya, program magang kepada mahasiswa, kegiatan Merdeka Belajar Kampus Merdeka (MBKM), workshop atau seminar, pengembangan kurikulum dan sebagainya.<\/p><p>Pada kesempatan ini Zurich Syariah turut menggelar Kuliah Tamu dengan tema \u201cTransformasi Digital dalam Asuransi Syariah: Mewujudkan Ekosistem Syariah yang Berdaya Saing dan Berkelanjutan.<\/p><p>Selain itu, Zurich Syariah juga memberikan secara simbolis berbagai produk asuransinya kepada pimpinan dan mahasiswa USK. Produk asuransi tersebut adalah Europa Travel Insurance untuk Rektor, Domestic Travel Insurance untuk 10 mahasiswa USK berprestasi, Asia Travel Insurance untuk Wakil Rektor dan Tim Kerja Sama USK, dan Personal Accident Insurance untuk semua peserta kuliah umum.<\/p>\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-32446b9 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"32446b9\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-af46918\" data-id=\"af46918\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-abdbb46 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"abdbb46\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\" data-e-bg-lazyload=\".elementor-background-overlay\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-51a2cca\" data-id=\"51a2cca\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-da7fcc4 elementor-widget elementor-widget-heading\" data-id=\"da7fcc4\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Alamat<\/h2>\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-element elementor-element-dcca92a elementor-widget elementor-widget-heading\" data-id=\"dcca92a\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Universitas Syiah Kuala\nJln. Teuku Nyak Arief\nDarussalam, Banda Aceh, Aceh, 23111, Indonesia\n<\/h2>\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-83e6f10\" data-id=\"83e6f10\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-86f92db elementor-widget elementor-widget-heading\" data-id=\"86f92db\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Tautan Penting<\/h2>\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-element elementor-element-aa62335 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"aa62335\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t<link rel=\"stylesheet\" href=\"https:\/\/kerjasama.usk.ac.id\/wp-content\/plugins\/elementor\/assets\/css\/widget-icon-list.min.css\">\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"http:\/\/simkerma.usk.ac.id\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-right\" viewBox=\"0 0 256 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224.3 273l-136 136c-9.4 9.4-24.6 9.4-33.9 0l-22.6-22.6c-9.4-9.4-9.4-24.6 0-33.9l96.4-96.4-96.4-96.4c-9.4-9.4-9.4-24.6 0-33.9L54.3 103c9.4-9.4 24.6-9.4 33.9 0l136 136c9.5 9.4 9.5 24.6.1 34z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Simkerma<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/laporankerma.kemdikbud.go.id\/auth\/login\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-right\" viewBox=\"0 0 256 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224.3 273l-136 136c-9.4 9.4-24.6 9.4-33.9 0l-22.6-22.6c-9.4-9.4-9.4-24.6 0-33.9l96.4-96.4-96.4-96.4c-9.4-9.4-9.4-24.6 0-33.9L54.3 103c9.4-9.4 24.6-9.4 33.9 0l136 136c9.5 9.4 9.5 24.6.1 34z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Laporan Kerma<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.usk.ac.id\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-right\" viewBox=\"0 0 256 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224.3 273l-136 136c-9.4 9.4-24.6 9.4-33.9 0l-22.6-22.6c-9.4-9.4-9.4-24.6 0-33.9l96.4-96.4-96.4-96.4c-9.4-9.4-9.4-24.6 0-33.9L54.3 103c9.4-9.4 24.6-9.4 33.9 0l136 136c9.5 9.4 9.5 24.6.1 34z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Universitas Syiah Kuala<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.oia.usk.ac.id\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-right\" viewBox=\"0 0 256 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224.3 273l-136 136c-9.4 9.4-24.6 9.4-33.9 0l-22.6-22.6c-9.4-9.4-9.4-24.6 0-33.9l96.4-96.4-96.4-96.4c-9.4-9.4-9.4-24.6 0-33.9L54.3 103c9.4-9.4 24.6-9.4 33.9 0l136 136c9.5 9.4 9.5 24.6.1 34z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Office of InternationaL Affairs (OIA)<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-element elementor-element-61c5209 elementor-widget elementor-widget-spacer\" data-id=\"61c5209\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t<style>\/*! elementor - v3.16.0 - 09-10-2023 *\/\n.elementor-column .elementor-spacer-inner{height:var(--spacer-size)}.e-con{--container-widget-width:100%}.e-con-inner>.elementor-widget-spacer,.e-con>.elementor-widget-spacer{width:var(--container-widget-width,var(--spacer-size));--align-self:var(--container-widget-align-self,initial);--flex-shrink:0}.e-con-inner>.elementor-widget-spacer>.elementor-widget-container,.e-con>.elementor-widget-spacer>.elementor-widget-container{height:100%;width:100%}.e-con-inner>.elementor-widget-spacer>.elementor-widget-container>.elementor-spacer,.e-con>.elementor-widget-spacer>.elementor-widget-container>.elementor-spacer{height:100%}.e-con-inner>.elementor-widget-spacer>.elementor-widget-container>.elementor-spacer>.elementor-spacer-inner,.e-con>.elementor-widget-spacer>.elementor-widget-container>.elementor-spacer>.elementor-spacer-inner{height:var(--container-widget-height,var(--spacer-size))}.e-con-inner>.elementor-widget-spacer.elementor-widget-empty,.e-con>.elementor-widget-spacer.elementor-widget-empty{position:relative;min-height:22px;min-width:22px}.e-con-inner>.elementor-widget-spacer.elementor-widget-empty .elementor-widget-empty-icon,.e-con>.elementor-widget-spacer.elementor-widget-empty .elementor-widget-empty-icon{position:absolute;top:0;bottom:0;left:0;right:0;margin:auto;padding:0;width:22px;height:22px}<\/style>\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-98d994a\" data-id=\"98d994a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-27cd55b elementor-widget elementor-widget-heading\" data-id=\"27cd55b\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Hubungi Kami<\/h2>\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-element elementor-element-74836d9 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"74836d9\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-phone-alt\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M497.39 361.8l-112-48a24 24 0 0 0-28 6.9l-49.6 60.6A370.66 370.66 0 0 1 130.6 204.11l60.6-49.6a23.94 23.94 0 0 0 6.9-28l-48-112A24.16 24.16 0 0 0 122.6.61l-104 24A24 24 0 0 0 0 48c0 256.5 207.9 464 464 464a24 24 0 0 0 23.4-18.6l24-104a24.29 24.29 0 0 0-14.01-27.6z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"> (0651) 755-3205<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-envelope\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M464 64H48C21.49 64 0 85.49 0 112v288c0 26.51 21.49 48 48 48h416c26.51 0 48-21.49 48-48V112c0-26.51-21.49-48-48-48zm0 48v40.805c-22.422 18.259-58.168 46.651-134.587 106.49-16.841 13.247-50.201 45.072-73.413 44.701-23.208.375-56.579-31.459-73.413-44.701C106.18 199.465 70.425 171.067 48 152.805V112h416zM48 400V214.398c22.914 18.251 55.409 43.862 104.938 82.646 21.857 17.205 60.134 55.186 103.062 54.955 42.717.231 80.509-37.199 103.053-54.947 49.528-38.783 82.032-64.401 104.947-82.653V400H48z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">kerjasama@usk.ac.id<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-globe\" viewBox=\"0 0 496 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M336.5 160C322 70.7 287.8 8 248 8s-74 62.7-88.5 152h177zM152 256c0 22.2 1.2 43.5 3.3 64h185.3c2.1-20.5 3.3-41.8 3.3-64s-1.2-43.5-3.3-64H155.3c-2.1 20.5-3.3 41.8-3.3 64zm324.7-96c-28.6-67.9-86.5-120.4-158-141.6 24.4 33.8 41.2 84.7 50 141.6h108zM177.2 18.4C105.8 39.6 47.8 92.1 19.3 160h108c8.7-56.9 25.5-107.8 49.9-141.6zM487.4 192H372.7c2.1 21 3.3 42.5 3.3 64s-1.2 43-3.3 64h114.6c5.5-20.5 8.6-41.8 8.6-64s-3.1-43.5-8.5-64zM120 256c0-21.5 1.2-43 3.3-64H8.6C3.2 212.5 0 233.8 0 256s3.2 43.5 8.6 64h114.6c-2-21-3.2-42.5-3.2-64zm39.5 96c14.5 89.3 48.7 152 88.5 152s74-62.7 88.5-152h-177zm159.3 141.6c71.4-21.2 129.4-73.7 158-141.6h-108c-8.8 56.9-25.6 107.8-50 141.6zM19.3 352c28.6 67.9 86.5 120.4 158 141.6-24.4-33.8-41.2-84.7-50-141.6h-108z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">kerjasama.usk.ac.id<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>USK dan Zurich Syariah Kolaborasi Perkuat Transformasi Digital Universitas Syiah Kuala dan Zurich Syariah siap berkolaborasi untuk memperkuat transformasi digital khususnya di bidang asuransi syariah. Komitmen ini ditandai dengan penandatanganan MoU oleh Rektor USK Prof. Dr. Ir. Marwan dengan Direktur Zurich Syariah Auralusia Rimadiana di Aula Fakultas Keperawatan USK. (Banda Aceh, 16 Oktober 2024). Business&#8230;<\/p>\n","protected":false},"author":2,"featured_media":3827,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_eb_attr":"","footnotes":""},"categories":[3],"tags":[],"class_list":["post-3825","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-berita"],"_links":{"self":[{"href":"https:\/\/kerjasama.usk.ac.id\/index.php\/wp-json\/wp\/v2\/posts\/3825","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kerjasama.usk.ac.id\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/kerjasama.usk.ac.id\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/kerjasama.usk.ac.id\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/kerjasama.usk.ac.id\/index.php\/wp-json\/wp\/v2\/comments?post=3825"}],"version-history":[{"count":4,"href":"https:\/\/kerjasama.usk.ac.id\/index.php\/wp-json\/wp\/v2\/posts\/3825\/revisions"}],"predecessor-version":[{"id":3832,"href":"https:\/\/kerjasama.usk.ac.id\/index.php\/wp-json\/wp\/v2\/posts\/3825\/revisions\/3832"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kerjasama.usk.ac.id\/index.php\/wp-json\/wp\/v2\/media\/3827"}],"wp:attachment":[{"href":"https:\/\/kerjasama.usk.ac.id\/index.php\/wp-json\/wp\/v2\/media?parent=3825"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/kerjasama.usk.ac.id\/index.php\/wp-json\/wp\/v2\/categories?post=3825"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/kerjasama.usk.ac.id\/index.php\/wp-json\/wp\/v2\/tags?post=3825"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}